{"id":53780,"date":"2025-09-17T16:37:00","date_gmt":"2025-09-17T14:37:00","guid":{"rendered":"https:\/\/arbrea-labs.com\/?p=53780"},"modified":"2025-09-22T12:43:56","modified_gmt":"2025-09-22T10:43:56","slug":"il-dottor-tommaso-pellegatta-sullanatomia-di-una-consultazione-che-converte","status":"publish","type":"post","link":"https:\/\/arbrea-labs.com\/it\/dr-tommaso-pellegatta-on-the-anatomy-of-a-consultation-that-converts\/","title":{"rendered":"Il dottor Tommaso Pellegatta su L'anatomia di un consulto che converte"},"content":{"rendered":"<div id=\"fws_6a0478f97ad48\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<p>Questo episodio di <a href=\"https:\/\/arbrea-labs.com\/it\/categoria\/colloqui-di-arbrea\/\">Colloqui Arbrea<\/a>, stiamo parlando con <a href=\"https:\/\/www.instagram.com\/drtomofficial\/?hl=en\">Dr. Pellegatta<\/a>, un chirurgo plastico che lavora presso Akademikliniken, una clinica leader nel settore della medicina estetica nordica. Le sue principali specialit\u00e0 sono gli interventi al seno, l'addominoplastica e il \"mommy makeover\". Tuttavia, oggi ci concentreremo sull'anatomia di un consulto che converte.<\/p>\n<h2><strong>Trasformare i consulti in viaggi incentrati sul paziente<\/strong><\/h2>\n<p>L'anatomia di un <a href=\"https:\/\/arbrea-labs.com\/it\/una-conversione-paga-labbonamento-ai-laboratori-arbrea\/\">consultazione che converte<\/a>. L'argomento principale di questo articolo \u00e8 la trasformazione della consultazione. Intendo dire di non concentrarsi sull'essere cos\u00ec tecnici. Parlare la lingua del paziente, non quella del medico. Questo lo rende un'esperienza che guida i pazienti verso il loro percorso estetico. E mi riferisco a un percorso che inizia prima del consulto e continua anche dopo. Nel complesso, \u00e8 un processo che coinvolge tutto ci\u00f2 che dico al paziente.<\/p>\n<h2><strong>Pi\u00f9 di un intervento chirurgico: Il vero valore della consulenza<\/strong><\/h2>\n<p>Per me, padroneggiare le consulenze <a href=\"https:\/\/arbrea-labs.com\/it\/arbrea-suite-il-vostro-partner-silenzioso-nella-sala-di-consultazione\/\">\u00e8 un must<\/a>. Aggiungerei che \u00e8 quasi altrettanto importante dell'intervento stesso. E per certi aspetti \u00e8 ancora pi\u00f9 importante. Perch\u00e9? Perch\u00e9 il consulto \u00e8 un momento in cui voi e il vostro paziente vi conoscete. Aiuta a creare fiducia, a capire veramente i loro desideri e ad aiutarli a realizzare ci\u00f2 che desiderano.<\/p>\n<p>Pertanto, un consulto non significa che un paziente entra con qualcosa in mente. Un desiderio che ha e noi lo realizziamo. \u00c8 un processo di trasformazione. Pi\u00f9 importante dell'intervento stesso. Tutti i chirurghi amano operare, e onestamente \u00e8 fantastico. Essere in grado di eseguire un aspetto cos\u00ec delicato e importante del percorso estetico del paziente.<\/p>\n<p>Tuttavia, la cosa pi\u00f9 importante \u00e8 ascoltare e capire veramente cosa vogliono i nostri pazienti. Non dobbiamo entrare in guerra con loro e imporre la nostra visione e i nostri desideri.<\/p>\n<h2><strong>Tagliare il rumore: Guidare i pazienti con chiarezza<\/strong><\/h2>\n<p>Un altro aspetto che ha reso pi\u00f9 complesso il percorso del paziente verso il suo aspetto ideale \u00e8 la quantit\u00e0 di informazioni disponibili. Questo ha contribuito a creare un<a href=\"https:\/\/arbrea-labs.com\/it\/con-la-suite-arbrea-i-pazienti-dubitano-del-loro-reale-concorrente\/\"> molta confusione<\/a> nei pazienti. Tutto ci\u00f2 si \u00e8 tradotto in un gran rumore intorno a ci\u00f2 che facciamo e al nostro lavoro. Ora dobbiamo affrontare un'altra sfida. Districarci tra il rumore e dare chiarezza ai nostri pazienti. In poche parole, essere la loro guida nel loro percorso estetico.<\/p>\n<p>Perch\u00e9 al giorno d'oggi su Internet si pu\u00f2 leggere di tutto. Ci sono molte opinioni, dal tipo di impianto che si dovrebbe avere al modo in cui si dovrebbe fare un certo intervento. Il problema \u00e8 che queste informazioni sono fortemente parziali. Forse sono opinioni di qualit\u00e0, ma non si applicano al caso specifico del paziente. Molte volte un paziente vuole qualcosa che non ha senso dal punto di vista anatomico. Non \u00e8 semplicemente fattibile per loro.<\/p>\n<p>\u00c8 questo il momento in cui interveniamo e li guidiamo con delicatezza. Spieghiamo ci\u00f2 che \u00e8 realisticamente fattibile e soddisfiamo le loro richieste e i loro desideri per quanto possibile.<\/p>\n<h2><strong>Dalle consultazioni della vecchia scuola ai viaggi guidati<\/strong><\/h2>\n<p>Condividiamo <a href=\"https:\/\/arbrea-labs.com\/it\/perche-arbrea-suites-ai-e-il-tassello-mancante-per-il-vostro-studio\/\">la stessa convinzione<\/a>. Che ogni paziente \u00e8 unico. So che Arbrea ha questa convinzione di base e cerca di condividerla con la comunit\u00e0 dei chirurghi plastici. So che alcuni dei miei colleghi sono scettici quando si parla di aggiornamenti. Perch\u00e9 vogliono che il consulto sia un momento in cui ascoltano il paziente, non per gestire le sue aspettative.<\/p>\n<p>Tuttavia, credo che questo concetto sia un po' vecchio. Penso che il consulto sia un ottimo momento per iniziare un percorso con i nostri pazienti. Per guidarli nella giusta direzione. Il nostro ruolo non \u00e8 quello di affermare che sar\u00e0 cos\u00ec e non in un altro modo. Questo modo di pensare \u00e8 davvero vecchio stampo. Inoltre, credo che far capire al paziente che cosa \u00e8 veramente fattibile gli dia tutta un'altra sensazione. Se si combinano le simulazioni 3D con l'intelligenza artificiale, si pu\u00f2 offrire al paziente un'esperienza completa. Possono persino vivere il loro sogno. E capire se \u00e8 quello che vogliono, o capire che vogliono qualcosa di leggermente diverso, purch\u00e9 sia fattibile.<\/p>\n<p>Quello che voglio dire \u00e8 che non dobbiamo fare i patrocinatori dei nostri pazienti ma <a href=\"https:\/\/arbrea-labs.com\/it\/state-respingendo-potenziali-pazienti-interessati-ai-vostri-servizi\/\">guidarli<\/a> e camminare insieme verso lo stesso obiettivo. E, soprattutto, evitare di imporre la nostra visione al paziente.<\/p>\n<p>Devo aggiungere che di solito i pazienti si rivolgono a chirurghi plastici con cui condividono la stessa visione. Il mio look \u00e8 naturale e piacevole e non sembra finto. Di solito i pazienti che vengono da me vogliono questi risultati. Naturalmente, in altre situazioni, i chirurghi plastici hanno gusti diversi e attirano un altro tipo di pazienti. \u00c8 molto bello, perch\u00e9 alla fine tutti sono soddisfatti.<\/p>\n<h2><strong>Come strutturo ogni consulenza in tre fasi per ottenere la massima chiarezza<\/strong><\/h2>\n<p>In realt\u00e0 curo e perfeziono ogni dettaglio della consulenza. Inoltre, divido la consulenza in 3 fasi. Posso farlo perch\u00e9 sono molto fortunato. Lavoro in una clinica accademica e abbiamo un processo gestito con cura attraverso diverse fasi. Cos\u00ec, quando il paziente viene da me, so come si presenta il suo stato di salute. Poich\u00e9 so gi\u00e0 tutto, posso passare direttamente alle parti importanti del consulto.<\/p>\n<h3>Il primo passo della consultazione, che considero anche il cuore della consultazione, \u00e8 rappresentato dai loro desideri e dalla loro volont\u00e0.<\/h3>\n<p>Il paziente arriva e la mia prima domanda, dopo averlo salutato, \u00e8: \u2018Quali sono i suoi desideri?\u2019. Naturalmente questi desideri possono essere qualsiasi cosa. Qualcosa di semplice. 3 o 4 frasi, come \u2018Voglio un seno naturale, non troppo grande, non troppo piccolo\u2019. Oppure qualcosa di molto elaborato. Ad esempio, ho dato un'occhiata in giro e qui ci sono 15 foto di ragazze in bikini che mi piacciono. In questa foto, mi piace questo, o in questa foto c'\u00e8 qualcosa di simile a quello che voglio ottenere con il mio nuovo look. La scollatura qui \u00e8 bella, ma non voglio che si veda il bordo della protesi. Per guidarli, mostro i risultati di interventi privati e chiedo cosa piace e cosa non piace. Questo mi aiuta a creare un'idea di massima di ci\u00f2 che desiderano.<\/p>\n<p>Per esempio, un impianto anatomico rotondo, se possibile, per ottenere un impianto pi\u00f9 proiettato. Un impianto che sporge un po' di pi\u00f9 dal corpo. Oppure, se desiderano un impianto pi\u00f9 piatto o qualcosa di simile, prenderei le loro misure e poi suggerirei.<\/p>\n<h3>La fase numero due \u00e8 quella che io chiamo \u201ceffetto wow\u201d, ovvero che in questo caso far\u00f2 sicuramente sentire questo effetto.<\/h3>\n<p>Ma cosa significa? Di solito combino la simulazione 3D e l'AI con le taglie. Cos\u00ec, allo stesso tempo, i pazienti li sentono su di s\u00e9 e hanno anche qualcuno che li guida su come appariranno, su come appariranno le loro nuove caratteristiche e su come appare la simulazione 3D da tutte le angolazioni. Inoltre, possono guardarsi davanti allo specchio con i sizer, sentire il peso dell'impianto e percepire come l'impianto potrebbe sentirsi con i vestiti addosso.<\/p>\n<h3>Nel frattempo, la fase numero tre \u00e8 la discussione di ci\u00f2 che accadr\u00e0 dopo l'intervento.<\/h3>\n<p>Io le chiamo praticit\u00e0, cio\u00e8 la parte pratica di questo viaggio estetico. I pazienti vedono tutto e decidono di procedere. Poi decidiamo l'impianto perfetto per loro. La mia ossessione \u00e8 trovare l'impianto perfetto per ogni mio paziente.<\/p>\n<p>Ma come sapete, possiamo sempre giocare. Provare a indossare una taglia leggermente pi\u00f9 grande o pi\u00f9 piccola. Non \u00e8 una grande differenza, ma lo facciamo. Soprattutto in alcuni casi di seno. Dovete essere pi\u00f9 specifiche, ma potete comunque provare diverse opzioni.<\/p>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"discover\"  data-column-margin=\"default\" data-midnight=\"dark\" data-top-percent=\"6%\" data-bottom-percent=\"6%\"  class=\"wpb_row vc_row-fluid vc_row full-width-section has-row-bg-color vc_row-o-equal-height vc_row-flex vc_row-o-content-middle\"  style=\"padding-top: calc(100vw * 0.06); padding-bottom: calc(100vw * 0.06); --row-bg-color: #ffffff;\"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop using-bg-color\"  style=\"background-color: #ffffff; \"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-8 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a0478f97b52b\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row  vc_custom_1504128844236\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column has-animation no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in-from-left\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<blockquote class=\"nectar_single_testimonial\" tabindex=\"0\" data-color=\"default\" data-style=\"bold\"><div class=\"inner\"> <p><span class=\"open-quote\">\u201d<\/span>Il nostro ruolo non \u00e8 quello di imporre la nostra visione, ma di guidare i pazienti e camminare insieme verso lo stesso obiettivo. <\/p><span class=\"wrap\"><span>Dott. Tommaso Pellegatta<\/span><\/span><\/div><\/blockquote>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-4 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"img-with-aniamtion-wrap  custom-size mask_shape_circle mask_size_contain\" data-max-width=\"175%\" data-max-width-mobile=\"default\" data-border-radius=\"10px\" data-shadow=\"none\" data-animation=\"grow-in\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <a href=\"https:\/\/www.instagram.com\/p\/DOd_pIICOvO\/?hl=en\" target=\"_self\" class=\"\">\n              <img decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"512\" width=\"768\" data-animation=\"grow-in\" src=\"https:\/\/arbrea-labs.com\/wp-content\/uploads\/2025\/09\/tommasopellegatta-1-768x512.jpg\" alt=\"Dott. Tommaso Pellegatta\" srcset=\"https:\/\/arbrea-labs.com\/wp-content\/uploads\/2025\/09\/tommasopellegatta-1-768x512.jpg 768w, https:\/\/arbrea-labs.com\/wp-content\/uploads\/2025\/09\/tommasopellegatta-1-300x200.jpg 300w, https:\/\/arbrea-labs.com\/wp-content\/uploads\/2025\/09\/tommasopellegatta-1-1024x683.jpg 1024w, https:\/\/arbrea-labs.com\/wp-content\/uploads\/2025\/09\/tommasopellegatta-1-1536x1024.jpg 1536w, https:\/\/arbrea-labs.com\/wp-content\/uploads\/2025\/09\/tommasopellegatta-1-18x12.jpg 18w, https:\/\/arbrea-labs.com\/wp-content\/uploads\/2025\/09\/tommasopellegatta-1-360x240.jpg 360w, https:\/\/arbrea-labs.com\/wp-content\/uploads\/2025\/09\/tommasopellegatta-1-900x600.jpg 900w, https:\/\/arbrea-labs.com\/wp-content\/uploads\/2025\/09\/tommasopellegatta-1-600x400.jpg 600w, https:\/\/arbrea-labs.com\/wp-content\/uploads\/2025\/09\/tommasopellegatta-1.jpg 1993w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\n            <\/a>\n          <\/div>\n        <\/div>\n        \n      <\/div>\n      <\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a0478f97bd27\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element  vc_custom_1758191551800\" >\n\t<h2><strong>Il cambiamento che ha cambiato i miei risultati (e l'esperienza dei miei pazienti)<\/strong><\/h2>\n<p>Da quando ho imparato questi tre passi, il mio <a href=\"https:\/\/arbrea-labs.com\/it\/il-costo-reale-del-mancato-adeguamento-ai-progressi-in-campo-medico-estetico\/\">i risultati sono ovviamente cambiati<\/a>. E all'inizio c'era una sorta di prima e dopo la consultazione. Quando ho iniziato, i miei consulti erano molto tecnici. Non usavo il gergo medico, ma erano comunque tecnici. E questo tipo di consultazioni annoiava davvero i pazienti. Dal nostro punto di vista, quello del medico, si pensa di essere scrupolosi e di dimostrare che i pazienti saranno in mani competenti. Tuttavia, i pazienti non capiscono molto di quello che state cercando di dire, si annoiano perch\u00e9, in fin dei conti, non gli interessa come lo fate. Vogliono che i loro desideri e le loro richieste siano esauditi. \u00c8 questa la cosa che cercano veramente.<\/p>\n<p>Quindi, naturalmente, quando ho cambiato il mio processo di consultazione e l'ho strutturato, ho ottenuto un tasso di conversione migliore. Tuttavia, la cosa pi\u00f9 importante per me era servire i miei pazienti in modo migliore. Perch\u00e9 la mia ossessione \u00e8 come rendere felici i miei pazienti e servirli meglio. Ecco perch\u00e9 continuo a cambiare e a migliorare le mie azioni in ogni parte del loro percorso estetico. Il processo di consultazione, l'intervento, l'assistenza post-operatoria. Tutto, insomma.<\/p>\n<h2><strong>Eccellenza attraverso un approccio incentrato sul paziente<\/strong><\/h2>\n<p>La gente mi chiede sempre se c'\u00e8 stato un momento determinante che mi ha spinto a cambiare. In realt\u00e0 no. Ho sempre applicato un approccio incentrato sul paziente. La cosa pi\u00f9 importante per me \u00e8 che i miei pazienti siano felici e soddisfatti di ci\u00f2 che offro loro. Naturalmente questo ti spinge a essere eccellente, perch\u00e9 l'unico modo per avere pazienti felici \u00e8 prendersi veramente cura di loro. E normalmente fare per loro pi\u00f9 di chiunque altro in termini di risultati\u2019. In fin dei conti, le critiche dei pazienti nei confronti del vostro studio o della vostra persona contano. Anche dal punto di vista dell'assistenza.<\/p>\n<p>Nessuno \u00e8 perfetto e a un certo punto un paziente potrebbe avere una complicazione o un nuovo intervento. Non \u00e8 colpa vostra o del vostro paziente. Perch\u00e9 dobbiamo ricordare che lavoriamo su persone, non su macchine. Non possiamo semplicemente aprire il cofano e ripararlo come se stessimo lavorando su un'automobile. Lavoriamo su corpi e i corpi reagiscono in modo diverso. Possiamo prevedere fino a 98% di ci\u00f2 che accadr\u00e0, ma quel 2% instabile non \u00e8 sotto il nostro controllo. Ecco perch\u00e9 \u00e8 nostro dovere sostenere i nostri pazienti e rassicurarli che le cose andranno bene. E che farete tutto il possibile per realizzare i loro desideri e le loro richieste.<\/p>\n<h2><strong>Perch\u00e9 Arbrea Suite ha cambiato il modo in cui guido i pazienti<\/strong><\/h2>\n<p>Sono passati quasi due anni da quando ho incorporato Arbrea Suite nel mio studio. E ha avuto un approccio rivoluzionario al mio processo di consultazione. Perch\u00e9? In questo modo l'intero consulto si svolge nella mia stanza e mi permette di proiettare l'aspetto che avranno i pazienti. Inoltre, posso far vedere loro direttamente ci\u00f2 che desiderano. Ad esempio, se uno dei miei pazienti dice: \u201cVoglio un impianto da 350 c.c. perch\u00e9 il mio amico ne ha uno uguale\u201d, gli faccio vedere come apparir\u00e0. In questo modo spiego visivamente perch\u00e9 non gli sta bene con un solo clic.<\/p>\n<p>Poi, con Arbrea, mostro loro ci\u00f2 di cui hanno bisogno. \u00c8 molto bello mostrare loro ci\u00f2 che \u00e8 possibile e ci\u00f2 che non lo \u00e8, sfatare diversi miti o confermare ci\u00f2 che funziona davvero per loro, ovvero che sta bene a loro.<\/p>\n<h2><strong>Arbrea Suite, una piattaforma di facile utilizzo supportata da un'assistenza reale<\/strong><\/h2>\n<p>Posso ammettere che l'utilizzo della piattaforma di Arbrea \u00e8 davvero intuitivo e semplice. Ho usato altre tecnologie e strumenti 3D. La differenza principale per me \u00e8 che con Arbrea posso simulare tutto. Tutto \u00e8 a portata di mano. \u00c8 facilissimo. L'interfaccia \u00e8 user-friendly e si pu\u00f2 imparare a usarla in pochissimo tempo. Anche se non si \u00e8 esperti di tecnologia, l'assistenza fornita \u00e8 straordinaria.<\/p>\n<p>Ho una bella storia per illustrare il mio punto di vista. Quando ho fatto le mie prime simulazioni, non sono rimasto affatto colpito dalla qualit\u00e0. Tuttavia, il problema riguardava l'illuminazione delle immagini, non il software in s\u00e9. Dopo aver parlato con uno dei membri del vostro team di vendita, Sara, e aver condiviso la mia frustrazione, ho scoperto come farlo correttamente. Le ho detto: \u201cS\u00ec, quando provo a mostrarlo direttamente al paziente, la qualit\u00e0 non \u00e8 delle migliori\u201d. Sara mi ha detto che le foto che stai scattando non sono le migliori da inserire nel software. Poi mi ha spiegato come scattare le foto con la giusta illuminazione. Da quel momento la differenza \u00e8 stata come il giorno e la notte.<\/p>\n<p>Ed \u00e8 anche una questione di pratica. \u00c8 necessario fare pratica con almeno 3 o 4 casi prima di farsi un'idea di come usarlo correttamente. 3 o 4 casi sono accettabili rispetto ai 1.000 casi che ho sentito per altri strumenti. Capisco che il vostro obiettivo sia quello di avere una soluzione avanzata, ma che non abbia una curva di apprendimento assurda. Altrimenti non la prenderemmo nemmeno in considerazione. Nonostante i vantaggi.<\/p>\n<h2><strong>Dalle recensioni alle simulazioni: Il nuovo processo di scoperta del paziente<\/strong><\/h2>\n<p>Ora c'\u00e8 un'altra parte importante di cui vorrei parlare. Si tratta del viaggio del paziente prima di arrivare al consulto. Il processo di scoperta. Questo aspetto \u00e8 molto importante. Anche se in realt\u00e0 non vediamo l'impatto che avr\u00e0 sul consulto e poi sull'intervento, ha un peso molto importante.<\/p>\n<p>Vanno online e controllano tutte le recensioni del medico su Google. Controllano le foto prima e dopo dei casi precedenti. Chiedono ad altri pazienti, tramite forum o comunit\u00e0, quale medico li ha operati e come \u00e8 stato il loro percorso. Questo li aiuta a farsi un'idea di massima.<\/p>\n<p>A volte vengono con suggerimenti per simulazioni o idee che aiutano la consultazione. Questa \u00e8 un'evoluzione in s\u00e9. Soprattutto se una paziente viene con le foto di un'altra ragazza in bikini che non mi aiutano affatto. O un'immagine di se stessa generata da ChatGPT, Sora, ecc.<\/p>\n<p>Per concludere, i pazienti quando vengono da voi sanno di voi, della vostra clinica, dei vostri registri e dei vostri pazienti felici. Poi vengono da voi e vedono anche la parte di simulazione.<\/p>\n<h2><strong>Conclusione<\/strong><\/h2>\n<p><a href=\"https:\/\/www.instagram.com\/p\/DOd_pIICOvO\/?hl=en\">In questo episodio<\/a> con la dottoressa Pellegatta, abbiamo visto che il consulto non \u00e8 pi\u00f9 solo il preludio all'intervento chirurgico. Sono il cuore dell'intero percorso estetico. Passando da conversazioni tecniche, incentrate sul medico, a esperienze incentrate sul paziente, creiamo non solo chiarezza e fiducia, ma anche un'autentica collaborazione.<\/p>\n<p>Con strumenti come Arbrea Suite, possiamo visualizzare i risultati, sfatare i miti e guidare i pazienti con trasparenza. Ma soprattutto, possiamo trasformare il consulto in un processo di trasformazione in cui i pazienti si sentono ascoltati, sostenuti e autorizzati a prendere decisioni informate.<\/p>\n<p>In fin dei conti, l'intervento chirurgico pu\u00f2 produrre un cambiamento fisico, ma \u00e8 il consulto che definisce il rapporto, stabilisce le aspettative e getta le basi per una soddisfazione duratura. Ecco perch\u00e9 il perfezionamento del consulto non riguarda solo le conversioni, ma la costruzione di un percorso in cui pazienti e chirurghi camminano insieme verso lo stesso obiettivo: risultati sicuri, naturali e veramente soddisfacenti.<\/p>\n<p>E per poterlo fare, \u00e8 necessario che Arbrea Suite sia presente nel vostro studio. <a href=\"https:\/\/arbrea-labs.com\/it\/iniziare-gratuitamente\/\">Iniziate a usarlo oggi stesso<\/a>!<\/p>\n<\/div>\n\n\n\n<div class=\"divider-wrap\" style=\"opacity: 0.57;\" data-alignment=\"default\"><div style=\"margin-top: 12.5px; height: 2px; margin-bottom: 12.5px;\" data-width=\"100%\" data-animate=\"yes\" data-animation-delay=\"\" data-color=\"default\" class=\"divider-border\"><\/div><\/div><div id=\"fws_6a0478f97c0f7\" data-midnight=\"\" data-column-margin=\"custom\" class=\"wpb_row vc_row-fluid vc_row inner_row vc_row-o-equal-height vc_row-flex vc_row-o-content-middle column-margin-7pct top_padding_tablet_7pct top_padding_phone_0px bottom_padding_tablet_7pct bottom_padding_phone_0px\"  style=\"padding-top: 6%; padding-bottom: 2%; \"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-4 wpb_column column_container vc_column_container col child_column left_padding_phone_10pct right_padding_phone_10pct\"    data-t-w-inherits=\"small_desktop\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap center custom-size mask_shape_circle mask_size_contain\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <a href=\"https:\/\/www.instagram.com\/reel\/C9fXFZaqc58\/?utm_source=ig_web_copy_link&#038;igsh=MzRlODBiNWFlZA==\" target=\"_self\" class=\"center\">\n              <img decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"996\" width=\"1024\" data-animation=\"none\" src=\"https:\/\/arbrea-labs.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-03-at-23.01.40-1024x996.jpeg\" alt=\"Dott. Tommaso Pellegatta\" srcset=\"https:\/\/arbrea-labs.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-03-at-23.01.40-1024x996.jpeg 1024w, https:\/\/arbrea-labs.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-03-at-23.01.40-300x292.jpeg 300w, https:\/\/arbrea-labs.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-03-at-23.01.40-768x747.jpeg 768w, https:\/\/arbrea-labs.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-03-at-23.01.40-12x12.jpeg 12w, https:\/\/arbrea-labs.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-03-at-23.01.40-360x350.jpeg 360w, https:\/\/arbrea-labs.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-03-at-23.01.40-600x584.jpeg 600w, https:\/\/arbrea-labs.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-03-at-23.01.40.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\n            <\/a>\n          <\/div>\n        <\/div>\n        \n      <\/div>\n      <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-8 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"    data-t-w-inherits=\"small_desktop\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-responsive-text font_size_max_32px font_size_desktop_2vw font_size_tablet_2vw font_size_phone_4vw font_line_height_1-5 nectar-link-underline-effect\"><h2><strong>Informazioni sul dottor Tommaso Pellegatta<\/strong><\/h2>\n<\/div><div class=\"nectar-responsive-text nectar-link-underline-effect\"><p><strong>Dott. Tommaso Pellegatta<\/strong> \u00e8 un illustre chirurgo plastico con una vasta esperienza in procedure estetiche e ricostruttive. Ha sede a Stoccolma presso <strong>Akademikliniken<\/strong>, \u00e8 specializzato in chirurgia del seno, addominoplastica e interventi combinati come il mommy makeover, puntando sempre su risultati naturali e armoniosi. <strong>Cofondatore<\/strong> di un'applicazione per la selezione degli impianti ampiamente utilizzata, nota come <strong>BAP<\/strong>, <strong>Dr. Pellegatta<\/strong> integra nel suo studio tecnologie all'avanguardia per migliorare la precisione e la soddisfazione del paziente. Conosciuto per il suo approccio empatico e incentrato sul paziente, d\u00e0 priorit\u00e0 alla creazione di un rapporto di fiducia fin dal primo consulto, assicurandosi che ogni piano di trattamento rifletta i desideri, le proporzioni e l'individualit\u00e0 del paziente. Parla correntemente lo svedese, l'inglese e l'italiano; \u00e8 inoltre membro attivo delle principali associazioni internazionali di chirurgia plastica e collabora regolarmente a pubblicazioni scientifiche e masterclass in tutto il mondo.<\/p>\n<\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"In questa puntata di Arbrea Talks parliamo con il dottor Pellegatta, chirurgo plastico che lavora presso l'Akademikliniken, una delle cliniche leader nel settore dell'estetica...","protected":false},"author":118,"featured_media":53723,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55],"tags":[],"class_list":["post-53780","post","type-post","status-publish","format-standard","has-post-thumbnail","category-arbrea-talks"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>The Anatomy of a Consultation that Converts with Arbrea Labs<\/title>\n<meta name=\"description\" content=\"Read more about how Dr. Tommaso Pellegatta manages to use Arbrea Labs&#039; solution to dissect the anatomy of a consultation that converts.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arbrea-labs.com\/it\/il-dottor-tommaso-pellegatta-sullanatomia-di-una-consultazione-che-converte\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dr. Tommaso Pellegatta on The Anatomy of a Consultation that Converts\" \/>\n<meta property=\"og:description\" content=\"Read more about how Dr. Tommaso Pellegatta manages to use Arbrea Labs&#039; solution to dissect the anatomy of a consultation that converts.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arbrea-labs.com\/it\/il-dottor-tommaso-pellegatta-sullanatomia-di-una-consultazione-che-converte\/\" \/>\n<meta property=\"og:site_name\" content=\"Arbrea Labs\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/arbrealabs\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-17T14:37:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-22T10:43:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arbrea-labs.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-03-at-23.01.40.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"1245\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/arbrea-labs.com\\\/dr-tommaso-pellegatta-on-the-anatomy-of-a-consultation-that-converts\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arbrea-labs.com\\\/dr-tommaso-pellegatta-on-the-anatomy-of-a-consultation-that-converts\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Dr. Tommaso Pellegatta on The Anatomy of a Consultation that Converts\",\"datePublished\":\"2025-09-17T14:37:00+00:00\",\"dateModified\":\"2025-09-22T10:43:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/arbrea-labs.com\\\/dr-tommaso-pellegatta-on-the-anatomy-of-a-consultation-that-converts\\\/\"},\"wordCount\":3895,\"publisher\":{\"@id\":\"https:\\\/\\\/arbrea-labs.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/arbrea-labs.com\\\/dr-tommaso-pellegatta-on-the-anatomy-of-a-consultation-that-converts\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arbrea-labs.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/WhatsApp-Image-2025-09-03-at-23.01.40.jpeg\",\"articleSection\":[\"Arbrea Talks\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/arbrea-labs.com\\\/dr-tommaso-pellegatta-on-the-anatomy-of-a-consultation-that-converts\\\/\",\"url\":\"https:\\\/\\\/arbrea-labs.com\\\/dr-tommaso-pellegatta-on-the-anatomy-of-a-consultation-that-converts\\\/\",\"name\":\"The Anatomy of a Consultation that Converts with Arbrea Labs\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arbrea-labs.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/arbrea-labs.com\\\/dr-tommaso-pellegatta-on-the-anatomy-of-a-consultation-that-converts\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/arbrea-labs.com\\\/dr-tommaso-pellegatta-on-the-anatomy-of-a-consultation-that-converts\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arbrea-labs.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/WhatsApp-Image-2025-09-03-at-23.01.40.jpeg\",\"datePublished\":\"2025-09-17T14:37:00+00:00\",\"dateModified\":\"2025-09-22T10:43:56+00:00\",\"description\":\"Read more about how Dr. Tommaso Pellegatta manages to use Arbrea Labs' solution to dissect the anatomy of a consultation that converts.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/arbrea-labs.com\\\/dr-tommaso-pellegatta-on-the-anatomy-of-a-consultation-that-converts\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/arbrea-labs.com\\\/dr-tommaso-pellegatta-on-the-anatomy-of-a-consultation-that-converts\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/arbrea-labs.com\\\/dr-tommaso-pellegatta-on-the-anatomy-of-a-consultation-that-converts\\\/#primaryimage\",\"url\":\"https:\\\/\\\/arbrea-labs.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/WhatsApp-Image-2025-09-03-at-23.01.40.jpeg\",\"contentUrl\":\"https:\\\/\\\/arbrea-labs.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/WhatsApp-Image-2025-09-03-at-23.01.40.jpeg\",\"width\":1280,\"height\":1245,\"caption\":\"Dr. Tommaso Pellegatta\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/arbrea-labs.com\\\/dr-tommaso-pellegatta-on-the-anatomy-of-a-consultation-that-converts\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/arbrea-labs.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dr. Tommaso Pellegatta on The Anatomy of a Consultation that Converts\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/arbrea-labs.com\\\/#website\",\"url\":\"https:\\\/\\\/arbrea-labs.com\\\/\",\"name\":\"Arbrea Labs\",\"description\":\"Augmented Reality &amp; 3D Solutions for Aesthetics\",\"publisher\":{\"@id\":\"https:\\\/\\\/arbrea-labs.com\\\/#organization\"},\"alternateName\":\"Arbrea\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/arbrea-labs.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/arbrea-labs.com\\\/#organization\",\"name\":\"Arbrea Labs\",\"alternateName\":\"Arbrea\",\"url\":\"https:\\\/\\\/arbrea-labs.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/arbrea-labs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/arbrea-labs.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo_arbrea_LABS-01-1-e1641392734450.png\",\"contentUrl\":\"https:\\\/\\\/arbrea-labs.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo_arbrea_LABS-01-1-e1641392734450.png\",\"width\":2000,\"height\":750,\"caption\":\"Arbrea Labs\"},\"image\":{\"@id\":\"https:\\\/\\\/arbrea-labs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/arbrealabs\",\"https:\\\/\\\/www.instagram.com\\\/arbrealabs\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/arbrea-labs-ag\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCbHN9gofXJv8rMAHcAguTcg\"],\"description\":\"Arbrea Labs leads the way in blending advanced AI technology with personalized healthcare. Our fast, simple and safe Augmented Reality & 3D simulators optimize consultations, saving time and enhancing patient education. Meanwhile, our AR-driven marketing booster enhances patient journeys, maximizing marketing ROI and fostering efficient lead generation. Join us as we shape the future of aesthetic healthcare.\",\"email\":\"info@arbrea-labs.com\",\"legalName\":\"Arbrea Labs AG\",\"foundingDate\":\"2018-03-04\",\"vatID\":\"CHE-292.633.177\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"}},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/7db487eef34efd49\\\/7db487eef34efd49arbrea-labs.com\\\/7db487eef34efd49it\\\/7db487eef34efd49author\\\/7db487eef34efd49\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"L'anatomia di un consulto che converte con Arbrea Labs","description":"Per saperne di pi\u00f9 su come il dottor Tommaso Pellegatta riesce a utilizzare la soluzione di Arbrea Labs per sezionare l'anatomia di un consulto che si converte.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arbrea-labs.com\/it\/il-dottor-tommaso-pellegatta-sullanatomia-di-una-consultazione-che-converte\/","og_locale":"it_IT","og_type":"article","og_title":"Dr. Tommaso Pellegatta on The Anatomy of a Consultation that Converts","og_description":"Read more about how Dr. Tommaso Pellegatta manages to use Arbrea Labs' solution to dissect the anatomy of a consultation that converts.","og_url":"https:\/\/arbrea-labs.com\/it\/il-dottor-tommaso-pellegatta-sullanatomia-di-una-consultazione-che-converte\/","og_site_name":"Arbrea Labs","article_publisher":"https:\/\/www.facebook.com\/arbrealabs","article_published_time":"2025-09-17T14:37:00+00:00","article_modified_time":"2025-09-22T10:43:56+00:00","og_image":[{"width":1280,"height":1245,"url":"https:\/\/arbrea-labs.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-03-at-23.01.40.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"","Tempo di lettura stimato":"13 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/arbrea-labs.com\/dr-tommaso-pellegatta-on-the-anatomy-of-a-consultation-that-converts\/#article","isPartOf":{"@id":"https:\/\/arbrea-labs.com\/dr-tommaso-pellegatta-on-the-anatomy-of-a-consultation-that-converts\/"},"author":{"name":"","@id":""},"headline":"Dr. Tommaso Pellegatta on The Anatomy of a Consultation that Converts","datePublished":"2025-09-17T14:37:00+00:00","dateModified":"2025-09-22T10:43:56+00:00","mainEntityOfPage":{"@id":"https:\/\/arbrea-labs.com\/dr-tommaso-pellegatta-on-the-anatomy-of-a-consultation-that-converts\/"},"wordCount":3895,"publisher":{"@id":"https:\/\/arbrea-labs.com\/#organization"},"image":{"@id":"https:\/\/arbrea-labs.com\/dr-tommaso-pellegatta-on-the-anatomy-of-a-consultation-that-converts\/#primaryimage"},"thumbnailUrl":"https:\/\/arbrea-labs.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-03-at-23.01.40.jpeg","articleSection":["Arbrea Talks"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/arbrea-labs.com\/dr-tommaso-pellegatta-on-the-anatomy-of-a-consultation-that-converts\/","url":"https:\/\/arbrea-labs.com\/dr-tommaso-pellegatta-on-the-anatomy-of-a-consultation-that-converts\/","name":"L'anatomia di un consulto che converte con Arbrea Labs","isPartOf":{"@id":"https:\/\/arbrea-labs.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/arbrea-labs.com\/dr-tommaso-pellegatta-on-the-anatomy-of-a-consultation-that-converts\/#primaryimage"},"image":{"@id":"https:\/\/arbrea-labs.com\/dr-tommaso-pellegatta-on-the-anatomy-of-a-consultation-that-converts\/#primaryimage"},"thumbnailUrl":"https:\/\/arbrea-labs.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-03-at-23.01.40.jpeg","datePublished":"2025-09-17T14:37:00+00:00","dateModified":"2025-09-22T10:43:56+00:00","description":"Per saperne di pi\u00f9 su come il dottor Tommaso Pellegatta riesce a utilizzare la soluzione di Arbrea Labs per sezionare l'anatomia di un consulto che si converte.","breadcrumb":{"@id":"https:\/\/arbrea-labs.com\/dr-tommaso-pellegatta-on-the-anatomy-of-a-consultation-that-converts\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arbrea-labs.com\/dr-tommaso-pellegatta-on-the-anatomy-of-a-consultation-that-converts\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/arbrea-labs.com\/dr-tommaso-pellegatta-on-the-anatomy-of-a-consultation-that-converts\/#primaryimage","url":"https:\/\/arbrea-labs.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-03-at-23.01.40.jpeg","contentUrl":"https:\/\/arbrea-labs.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-03-at-23.01.40.jpeg","width":1280,"height":1245,"caption":"Dr. Tommaso Pellegatta"},{"@type":"BreadcrumbList","@id":"https:\/\/arbrea-labs.com\/dr-tommaso-pellegatta-on-the-anatomy-of-a-consultation-that-converts\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/arbrea-labs.com\/"},{"@type":"ListItem","position":2,"name":"Dr. Tommaso Pellegatta on The Anatomy of a Consultation that Converts"}]},{"@type":"WebSite","@id":"https:\/\/arbrea-labs.com\/#website","url":"https:\/\/arbrea-labs.com\/","name":"Laboratori Arbrea","description":"Soluzioni di realt\u00e0 aumentata e 3D per l'estetica","publisher":{"@id":"https:\/\/arbrea-labs.com\/#organization"},"alternateName":"Arbrea","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arbrea-labs.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/arbrea-labs.com\/#organization","name":"Laboratori Arbrea","alternateName":"Arbrea","url":"https:\/\/arbrea-labs.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/arbrea-labs.com\/#\/schema\/logo\/image\/","url":"https:\/\/arbrea-labs.com\/wp-content\/uploads\/2022\/01\/logo_arbrea_LABS-01-1-e1641392734450.png","contentUrl":"https:\/\/arbrea-labs.com\/wp-content\/uploads\/2022\/01\/logo_arbrea_LABS-01-1-e1641392734450.png","width":2000,"height":750,"caption":"Arbrea Labs"},"image":{"@id":"https:\/\/arbrea-labs.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/arbrealabs","https:\/\/www.instagram.com\/arbrealabs\/","https:\/\/www.linkedin.com\/company\/arbrea-labs-ag\/","https:\/\/www.youtube.com\/channel\/UCbHN9gofXJv8rMAHcAguTcg"],"description":"Arbrea Labs \u00e8 all'avanguardia nella fusione tra tecnologia AI avanzata e assistenza sanitaria personalizzata. I nostri simulatori di Realt\u00e0 Aumentata e 3D, veloci, semplici e sicuri, ottimizzano le consultazioni, facendo risparmiare tempo e migliorando l'educazione dei pazienti. Nel frattempo, il nostro marketing guidato dall'AR migliora il percorso del paziente, massimizzando il ROI del marketing e favorendo un'efficiente lead generation. Unitevi a noi nel plasmare il futuro dell'assistenza sanitaria estetica.","email":"info@arbrea-labs.com","legalName":"Arbrea Labs AG","foundingDate":"2018-03-04","vatID":"CHE-292.633.177","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}},{"@type":"Person","@id":"","url":"https:\/7db487eef34efd49\/7db487eef34efd49arbrea-labs.com\/7db487eef34efd49it\/7db487eef34efd49author\/7db487eef34efd49"}]}},"_links":{"self":[{"href":"https:\/\/arbrea-labs.com\/it\/wp-json\/wp\/v2\/posts\/53780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arbrea-labs.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arbrea-labs.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arbrea-labs.com\/it\/wp-json\/wp\/v2\/users\/118"}],"replies":[{"embeddable":true,"href":"https:\/\/arbrea-labs.com\/it\/wp-json\/wp\/v2\/comments?post=53780"}],"version-history":[{"count":0,"href":"https:\/\/arbrea-labs.com\/it\/wp-json\/wp\/v2\/posts\/53780\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arbrea-labs.com\/it\/wp-json\/wp\/v2\/media\/53723"}],"wp:attachment":[{"href":"https:\/\/arbrea-labs.com\/it\/wp-json\/wp\/v2\/media?parent=53780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arbrea-labs.com\/it\/wp-json\/wp\/v2\/categories?post=53780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arbrea-labs.com\/it\/wp-json\/wp\/v2\/tags?post=53780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}