{"id":39190,"date":"2024-11-08T17:37:54","date_gmt":"2024-11-08T16:37:54","guid":{"rendered":"https:\/\/arbrea-labs.com\/?p=39190"},"modified":"2025-02-20T17:34:32","modified_gmt":"2025-02-20T16:34:32","slug":"die-versteckten-risiken-der-verwendung-von-externen-sizern-und-vorher-nachher-fotos-bei-asthetischen-beratungen","status":"publish","type":"post","link":"https:\/\/arbrea-labs.com\/de\/the-hidden-risks-of-relying-on-external-sizers-and-before-and-after-photos-in-aesthetic-consultations\/","title":{"rendered":"Die versteckten Risiken der Verwendung von externen Gr\u00f6\u00dfen und Vorher-Nachher-Fotos bei \u00e4sthetischen Beratungen"},"content":{"rendered":"<div id=\"fws_6a048de627b7c\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<p class=\"p1\">Lieber Doktor,<\/p>\n<p class=\"p1\">Lassen Sie uns ein offenes Wort miteinander reden. Ich wei\u00df, dass Sie Ihr Bestes tun, um den Patienten ein Bild davon zu vermitteln, was sie erwarten k\u00f6nnen, und Sie tun das wahrscheinlich schon seit Jahren. Aber lassen Sie uns Klartext reden: Einige dieser altmodischen Methoden, wie <strong>Externe Sizer und Vorher-Nachher-Fotos<\/strong>, <strong>sind wie Kassetten in einer Welt von Spotify<\/strong>. Sie m\u00f6gen zuverl\u00e4ssig und sogar bequem erscheinen, aber sie bergen versteckte Risiken und bieten den Patienten im Jahr 2024 nicht das, was sie verdient haben.<\/p>\n<p class=\"p1\">Nun, ich verstehe es - Technologie ist ein Sprung. Es ist einfach, bei dem zu bleiben, was man kennt. Aber seien Sie mir nicht b\u00f6se, Doktor, und lassen Sie uns einen Blick darauf werfen, was diese digitalen Tools f\u00fcr Ihre Praxis - und Ihre Patienten - tun k\u00f6nnen, was die alten Methoden nicht k\u00f6nnen.<\/p>\n<h3 class=\"p1\"><strong>Externe Sizer: Hey, schau mal! Eine Gr\u00f6\u00dfe, die nicht deine sein wird!<\/strong><\/h3>\n<p class=\"p1\">Externe Sizer: Man setzt einen ein, und die Patienten erhalten eine ungef\u00e4hre Vorstellung davon, wie ein Implantat oder eine Ver\u00e4nderung aussehen k\u00f6nnte. Aber hier ist der Haken:<\/p>\n<ul>\n<li class=\"p1\"><strong>Es ist nur eine Vermutung:<\/strong> Ein externer Sizer ist nur eine Illusion, eine billige T\u00e4uschung des Auges. Sie zeigen den Patienten eine Ann\u00e4herung, eine \"beste Sch\u00e4tzung\", wie ihre Ergebnisse aussehen k\u00f6nnten. Aber wir reden hier \u00fcber eine Operation, nicht \u00fcber ein Halloween-Kost\u00fcm. Raten sollte kein Teil der Gleichung sein.<\/li>\n<li class=\"p1\"><strong>Vorbereitung auf eine Entt\u00e4uschung<\/strong>: Externe Sizer ber\u00fccksichtigen nicht die individuelle Anatomie - Knochenstruktur, Hautelastizit\u00e4t und so weiter. Wenn die Ergebnisse also nicht so aussehen wie das \"ungef\u00e4hre\" Bild, das sie im Spiegel gesehen haben, sind die Patienten nicht begeistert. Und niemand m\u00f6chte einen entt\u00e4uschten Patienten haben.<\/li>\n<li class=\"p1\"><strong>Vergessen wir nicht den Faktor der Unbeholfenheit<\/strong>: Niemand \"mag\" es wirklich, etwas in seinen BH zu stecken oder das Gef\u00fchl zu haben, Teile seiner Zukunft \"anzuprobieren\". Es ist unangenehm, es ist peinlich, und, ehrlich gesagt, es ist ein alter Hut.<\/li>\n<\/ul>\n<p class=\"p1\">Mit AR und 3D k\u00f6nnen sich Patienten in Echtzeit genau so sehen, wie sie nach der Operation aussehen k\u00f6nnten. Keine groben Ann\u00e4herungen, kein R\u00e4tselraten - nur eine ehrliche Ansicht, die einzigartig f\u00fcr ihren eigenen K\u00f6rper ist. H\u00f6rt sich das nicht nach einer besseren Idee an?<\/p>\n<h3 class=\"p1\"><strong>Vorher-Nachher-Fotos: Ein veraltetes Ratespiel<\/strong><\/h3>\n<p class=\"p1\">Ah, die bew\u00e4hrten Vorher-Nachher-Fotos. Sie sind ein klassischer Schachzug, als w\u00fcrde man einem Kind ein Bild von Disneyland zeigen und sagen: \"So sieht ein Urlaub aus.\" Nur ist jeder Patient einzigartig, und was bei dem einen funktioniert hat, muss bei einem anderen nicht immer funktionieren. Vorher-Nachher-Ansichten schaden oft mehr als sie n\u00fctzen.<\/p>\n<ul>\n<li class=\"p1\"><strong>\u00c4pfel und Orangen<\/strong>: Die Anatomie und der Heilungsprozess eines jeden Menschen sind einzigartig. Wenn man den Patienten die Ergebnisse anderer zeigt, ist das so, als w\u00fcrde man sagen: \"Sie werden so aussehen\", obwohl das in Wirklichkeit nicht der Fall ist. Das f\u00fchrt zu entt\u00e4uschten Hoffnungen und einer Menge Fragen.<\/li>\n<li class=\"p1\"><strong>Fehlinterpretationen aller Art:<\/strong> Die Patienten sehen ein Ergebnis und denken, dass sie eine Kopie davon bekommen werden. Aber das ist nicht der Fall. Jetzt sind sie verwirrt und entt\u00e4uscht. Und pl\u00f6tzlich haben Sie es mit Konsequenzen zu tun, die Sie mit einem einfachen digitalen Tool h\u00e4tten vermeiden k\u00f6nnen.<\/li>\n<li class=\"p1\"><strong>Eingeschr\u00e4nkte Bildung<\/strong>: Statische Fotos zeigen keine Bewegung, keine Personalisierung oder eine 3D-Ansicht ihres zuk\u00fcnftigen Ichs. Vorher-Nachher-Fotos vermitteln ihnen eine flache, zweidimensionale Ansicht, und das reicht einfach nicht aus.<\/li>\n<\/ul>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"discover\"  data-column-margin=\"default\" data-midnight=\"dark\" data-top-percent=\"6%\" data-bottom-percent=\"6%\"  class=\"wpb_row vc_row-fluid vc_row full-width-section has-row-bg-color vc_row-o-equal-height vc_row-flex vc_row-o-content-middle\"  style=\"padding-top: calc(100vw * 0.06); padding-bottom: calc(100vw * 0.06); --row-bg-color: #ffffff;\"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop using-bg-color\"  style=\"background-color: #ffffff; \"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-8 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a048de6281b2\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row  vc_custom_1504128844236\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column has-animation no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in-from-left\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<blockquote class=\"nectar_single_testimonial\" tabindex=\"0\" data-color=\"default\" data-style=\"bold\"><div class=\"inner\"> <p><span class=\"open-quote\">\u201d<\/span>Die Patienten wollen Transparenz. Mit AR sagen Sie: \"Hey, ich habe nichts zu verbergen. <\/p><div role=\"presentation\" data-shadow=\"\" class=\"image-icon\" style=\"background-image: url(https:\/\/arbrea-labs.com\/wp-content\/uploads\/2024\/06\/Untitled-design-40-300x300.png);\"><\/div><span class=\"wrap\"><span>Guilherme De Souza<\/span><span class=\"title\">Leiter des weltweiten Vertriebs - Arbrea Labs<\/span><\/span><\/div><\/blockquote>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-4 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"img-with-aniamtion-wrap  custom-size mask_shape_circle mask_size_contain mask_alignment_desktop_center-center\" data-max-width=\"175%\" data-max-width-mobile=\"default\" data-border-radius=\"10px\" data-shadow=\"none\" data-animation=\"grow-in\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <a href=\"https:\/\/www.linkedin.com\/in\/guidesouzabcn\/\" target=\"_self\" class=\"\">\n              <img decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"576\" width=\"768\" data-animation=\"grow-in\" src=\"https:\/\/arbrea-labs.com\/wp-content\/uploads\/2024\/07\/Untitled-design-75-768x576.png\" alt=\"brust 3d modell\" srcset=\"https:\/\/arbrea-labs.com\/wp-content\/uploads\/2024\/07\/Untitled-design-75-768x576.png 768w, https:\/\/arbrea-labs.com\/wp-content\/uploads\/2024\/07\/Untitled-design-75-300x225.png 300w, https:\/\/arbrea-labs.com\/wp-content\/uploads\/2024\/07\/Untitled-design-75-600x450.png 600w, https:\/\/arbrea-labs.com\/wp-content\/uploads\/2024\/07\/Untitled-design-75.png 1024w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\n            <\/a>\n          <\/div>\n        <\/div>\n        \n      <\/div>\n      <\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a048de628eb8\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element  vc_custom_1731085934071\" >\n\t<h3 class=\"p1\"><strong>Wie AR und 3D-Visualisierung das Spiel ver\u00e4ndern k\u00f6nnen<\/strong><\/h3>\n<p class=\"p1\">Kommen wir gleich zur Sache - unser <a href=\"https:\/\/arbrea-labs.com\/de\/was-wir-bauen\/brustsimulator\/\">AR- und 3D-Werkzeuge<\/a> von Arbrea Labs l\u00f6sen diese Probleme. Sie erm\u00f6glichen Ihnen eine transparente, pr\u00e4zise und auf den einzelnen Patienten zugeschnittene Konsultation.<\/p>\n<ul>\n<li class=\"p1\"><strong>Dynamisch und in Echtzeit<\/strong>: Mit AR sehen die Patienten *sich selbst* in Echtzeit, nicht nur ein zuf\u00e4lliges Modell. Sie bekommen ein Gef\u00fchl daf\u00fcr, wie sie aussehen werden, und zwar auf ehrliche, genaue und tats\u00e4chlich personalisierte Weise. Es ist, als w\u00fcrde man den Patienten auf eine Tour durch sein zuk\u00fcnftiges Ich mitnehmen.<\/li>\n<li class=\"p1\"><strong>Pr\u00e4zision auf einem neuen Niveau<\/strong>: Mit 3D-Tools erhalten die Patienten nicht nur eine Vorstellung von ihrem potenziellen Ergebnis, sondern sehen ihre eigenen einzigartigen anatomischen Merkmale genau dargestellt. Sie sehen das echte Ergebnis - keine Vermutungen, keine Annahmen.<\/li>\n<li class=\"p1\"><strong>Keine unangenehmen Probel\u00e4ufe mehr<\/strong>: Mit einem Bildschirm, ein paar Fingertipps und etwas digitaler Magie geben Sie Ihren Patienten eine informierte, hochtechnologische Vorschau, ohne das ganze unangenehme R\u00e4tselraten.<\/li>\n<\/ul>\n<h3 class=\"p1\"><strong>Transparenz schafft Vertrauen, und Technologie schafft Transparenz<\/strong><\/h3>\n<p class=\"p1\">Seien wir ehrlich: Die Patienten von heute wollen Ehrlichkeit. Sie wollen klare Antworten, realistische Erwartungen und ein Verst\u00e4ndnis daf\u00fcr, was im Behandlungsraum passiert. Und der Einsatz von AR- und 3D-Tools? Es ist, als w\u00fcrde man ihnen sagen: \"Hey, ich habe nichts zu verbergen.\" Es zeigt, dass Sie auf dem neuesten Stand der Technik sind, und gibt ihnen das Gef\u00fchl, dass sie in den H\u00e4nden von jemandem sind, der der Zeit voraus ist. Die Patienten von heute wollen Transparenz und die Gewissheit, dass sie sich in guten, sachkundigen H\u00e4nden befinden.<\/p>\n<h3 class=\"p1\"><strong>Werden wir also digital? Partner mit uns f\u00fcr den Erfolg!<\/strong><\/h3>\n<p class=\"p1\">Bei der Umstellung auf AR und 3D geht es nicht nur um den Wechsel von Werkzeugen, sondern auch darum, die Art und Weise, wie Sie mit Ihren Patienten in Kontakt treten und sie unterst\u00fctzen, neu zu gestalten. Bei Arbrea Labs sorgen wir f\u00fcr einen nahtlosen \u00dcbergang - Unterst\u00fctzung, Schulung, das ganze Paket - damit Sie mit digitaler Magie ausgestattet sind.<\/p>\n<p class=\"p1\">Also, Herr Doktor, wenn Sie immer noch daran denken, an den alten Methoden festzuhalten, lassen Sie uns ein wenig plaudern. Das ist Ihre Chance, den Schritt in die Zukunft zu wagen, Ihre Patienten zu unterst\u00fctzen und Ihre Praxis von anderen abzuheben.<\/p>\n<p class=\"p1\">Mit AR und 3D stellen wir uns die Zukunft der \u00e4sthetischen Medizin nicht nur vor, wir erschaffen sie hier und jetzt. Sind Sie bereit, Ihre Praxis auf die n\u00e4chste Stufe zu heben? <a href=\"https:\/\/arbrea-labs.com\/de\/kostenlos-loslegen\/\">Jetzt loslegen<\/a>!<\/p>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a048de62929b\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"divider-wrap\" style=\"opacity: 0.57;\" data-alignment=\"default\"><div style=\"margin-top: 12.5px; height: 2px; margin-bottom: 12.5px;\" data-width=\"100%\" data-animate=\"yes\" data-animation-delay=\"\" data-color=\"default\" class=\"divider-border\"><\/div><\/div><div id=\"fws_6a048de629493\" data-midnight=\"\" data-column-margin=\"custom\" class=\"wpb_row vc_row-fluid vc_row inner_row vc_row-o-equal-height vc_row-flex vc_row-o-content-middle column-margin-7pct top_padding_tablet_7pct top_padding_phone_0px bottom_padding_tablet_7pct bottom_padding_phone_0px\"  style=\"padding-top: 6%; padding-bottom: 2%; \"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-4 wpb_column column_container vc_column_container col child_column left_padding_phone_10pct right_padding_phone_10pct\"    data-t-w-inherits=\"small_desktop\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap center mask_shape_circle mask_size_contain\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <a href=\"https:\/\/www.linkedin.com\/in\/guidesouzabcn\/\" target=\"_self\" class=\"center\">\n              <img decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"100\" width=\"100\" data-animation=\"none\" src=\"\" alt=\"\"  \/>\n            <\/a>\n          <\/div>\n        <\/div>\n        \n      <\/div>\n      <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-8 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"    data-t-w-inherits=\"small_desktop\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-responsive-text font_size_max_32px font_size_desktop_2vw font_size_tablet_2vw font_size_phone_4vw font_line_height_1-5 nectar-link-underline-effect\"><h2><strong>\u00dcber Guilherme De Souza<\/strong><\/h2>\n<\/div><div class=\"nectar-responsive-text nectar-link-underline-effect\"><p>Guilherme de Souza ist Head of Global Sales bei Arbrea Labs und verf\u00fcgt \u00fcber mehr als 15 Jahre Erfahrung bei der Entwicklung neuer Technologien in der \u00c4sthetikbranche. Guilherme ist f\u00fcr seinen strategischen Weitblick und seine fundierten Kenntnisse in diesem Bereich bekannt. Er hat Kliniken und Fachleuten ma\u00dfgeblich dabei geholfen, modernste L\u00f6sungen zu integrieren, um die Erfahrungen der Patienten und die klinischen Ergebnisse zu verbessern.<\/p>\n<\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"Sehr geehrter Herr Doktor, lassen Sie uns ein offenes Wort reden. Ich wei\u00df, dass Sie Ihr Bestes tun, um den Patienten ein Bild von dem zu vermitteln, was sie erwarten k\u00f6nnen, und Sie...","protected":false},"author":3,"featured_media":39200,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[306],"tags":[],"class_list":["post-39190","post","type-post","status-publish","format-standard","has-post-thumbnail","category-marketing-sales-tips"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>External Sizers: Are They Outdated in the Modern World? - Arbrea Labs<\/title>\n<meta name=\"description\" content=\"Stay ahead in the world of plastic surgery. Learn why traditional methods like external sizers are being replaced by more advanced techniques.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arbrea-labs.com\/de\/die-versteckten-risiken-der-verwendung-von-externen-sizern-und-vorher-nachher-fotos-bei-asthetischen-beratungen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Hidden Risks of Relying on External Sizers and Before-and-After Photos in Aesthetic Consultations\" \/>\n<meta property=\"og:description\" content=\"Stay ahead in the world of plastic surgery. Learn why traditional methods like external sizers are being replaced by more advanced techniques.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arbrea-labs.com\/de\/die-versteckten-risiken-der-verwendung-von-externen-sizern-und-vorher-nachher-fotos-bei-asthetischen-beratungen\/\" \/>\n<meta property=\"og:site_name\" content=\"Arbrea Labs\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/arbrealabs\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-08T16:37:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-20T16:34:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arbrea-labs.com\/wp-content\/uploads\/2024\/11\/Untitled-design-2024-11-08T175559.659.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Selene Cabibbo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Selene Cabibbo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/arbrea-labs.com\\\/the-hidden-risks-of-relying-on-external-sizers-and-before-and-after-photos-in-aesthetic-consultations\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arbrea-labs.com\\\/the-hidden-risks-of-relying-on-external-sizers-and-before-and-after-photos-in-aesthetic-consultations\\\/\"},\"author\":{\"name\":\"Selene Cabibbo\",\"@id\":\"https:\\\/\\\/arbrea-labs.com\\\/#\\\/schema\\\/person\\\/016c4a63167f71667e28da2b91c9e25d\"},\"headline\":\"The Hidden Risks of Relying on External Sizers and Before-and-After Photos in Aesthetic Consultations\",\"datePublished\":\"2024-11-08T16:37:54+00:00\",\"dateModified\":\"2025-02-20T16:34:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/arbrea-labs.com\\\/the-hidden-risks-of-relying-on-external-sizers-and-before-and-after-photos-in-aesthetic-consultations\\\/\"},\"wordCount\":2358,\"publisher\":{\"@id\":\"https:\\\/\\\/arbrea-labs.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/arbrea-labs.com\\\/the-hidden-risks-of-relying-on-external-sizers-and-before-and-after-photos-in-aesthetic-consultations\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arbrea-labs.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Untitled-design-2024-11-08T175559.659.png\",\"articleSection\":[\"Marketing &amp; Sales Tips\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/arbrea-labs.com\\\/the-hidden-risks-of-relying-on-external-sizers-and-before-and-after-photos-in-aesthetic-consultations\\\/\",\"url\":\"https:\\\/\\\/arbrea-labs.com\\\/the-hidden-risks-of-relying-on-external-sizers-and-before-and-after-photos-in-aesthetic-consultations\\\/\",\"name\":\"External Sizers: Are They Outdated in the Modern World? - Arbrea Labs\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arbrea-labs.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/arbrea-labs.com\\\/the-hidden-risks-of-relying-on-external-sizers-and-before-and-after-photos-in-aesthetic-consultations\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/arbrea-labs.com\\\/the-hidden-risks-of-relying-on-external-sizers-and-before-and-after-photos-in-aesthetic-consultations\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arbrea-labs.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Untitled-design-2024-11-08T175559.659.png\",\"datePublished\":\"2024-11-08T16:37:54+00:00\",\"dateModified\":\"2025-02-20T16:34:32+00:00\",\"description\":\"Stay ahead in the world of plastic surgery. Learn why traditional methods like external sizers are being replaced by more advanced techniques.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/arbrea-labs.com\\\/the-hidden-risks-of-relying-on-external-sizers-and-before-and-after-photos-in-aesthetic-consultations\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/arbrea-labs.com\\\/the-hidden-risks-of-relying-on-external-sizers-and-before-and-after-photos-in-aesthetic-consultations\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/arbrea-labs.com\\\/the-hidden-risks-of-relying-on-external-sizers-and-before-and-after-photos-in-aesthetic-consultations\\\/#primaryimage\",\"url\":\"https:\\\/\\\/arbrea-labs.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Untitled-design-2024-11-08T175559.659.png\",\"contentUrl\":\"https:\\\/\\\/arbrea-labs.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Untitled-design-2024-11-08T175559.659.png\",\"width\":1920,\"height\":1080,\"caption\":\"External Sizers\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/arbrea-labs.com\\\/the-hidden-risks-of-relying-on-external-sizers-and-before-and-after-photos-in-aesthetic-consultations\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/arbrea-labs.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The Hidden Risks of Relying on External Sizers and Before-and-After Photos in Aesthetic Consultations\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/arbrea-labs.com\\\/#website\",\"url\":\"https:\\\/\\\/arbrea-labs.com\\\/\",\"name\":\"Arbrea Labs\",\"description\":\"Augmented Reality &amp; 3D Solutions for Aesthetics\",\"publisher\":{\"@id\":\"https:\\\/\\\/arbrea-labs.com\\\/#organization\"},\"alternateName\":\"Arbrea\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/arbrea-labs.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/arbrea-labs.com\\\/#organization\",\"name\":\"Arbrea Labs\",\"alternateName\":\"Arbrea\",\"url\":\"https:\\\/\\\/arbrea-labs.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/arbrea-labs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/arbrea-labs.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo_arbrea_LABS-01-1-e1641392734450.png\",\"contentUrl\":\"https:\\\/\\\/arbrea-labs.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo_arbrea_LABS-01-1-e1641392734450.png\",\"width\":2000,\"height\":750,\"caption\":\"Arbrea Labs\"},\"image\":{\"@id\":\"https:\\\/\\\/arbrea-labs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/arbrealabs\",\"https:\\\/\\\/www.instagram.com\\\/arbrealabs\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/arbrea-labs-ag\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCbHN9gofXJv8rMAHcAguTcg\"],\"description\":\"Arbrea Labs leads the way in blending advanced AI technology with personalized healthcare. Our fast, simple and safe Augmented Reality & 3D simulators optimize consultations, saving time and enhancing patient education. Meanwhile, our AR-driven marketing booster enhances patient journeys, maximizing marketing ROI and fostering efficient lead generation. Join us as we shape the future of aesthetic healthcare.\",\"email\":\"info@arbrea-labs.com\",\"legalName\":\"Arbrea Labs AG\",\"foundingDate\":\"2018-03-04\",\"vatID\":\"CHE-292.633.177\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/arbrea-labs.com\\\/#\\\/schema\\\/person\\\/016c4a63167f71667e28da2b91c9e25d\",\"name\":\"Selene Cabibbo\",\"description\":\"Selene Cabibbo is the Marketing Manager at Arbrea Labs, specializing in driving growth through innovative marketing strategies. With a strong focus on promoting AR and 3D simulation technologies for plastic surgery, she is dedicated to elevating the brand's presence and connecting with audiences worldwide.\",\"sameAs\":[\"http:\\\/\\\/arbrea-labs.com\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/selene-cabibbo\\\/\"],\"knowsAbout\":[\"Copywriting\",\"Marketing strategy\",\"Digital Marketing\",\"Healthcare Marketing\",\"Medical Aesthetic Marketing\",\"Plastic Surgery Marketing\",\"SEO\",\"Social Media Management\"],\"knowsLanguage\":[\"Italian\",\"English\",\"Spanish\"],\"jobTitle\":\"Marketing Manager\",\"url\":\"https:\\\/\\\/arbrea-labs.com\\\/de\\\/author\\\/d2eea4cfe95a969b\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Externe Sizer: Sind sie in der modernen Welt \u00fcberholt? - Arbrea-Labore","description":"Bleiben Sie in der Welt der plastischen Chirurgie auf dem Laufenden. Erfahren Sie, warum traditionelle Methoden wie externe Sizer durch modernere Techniken ersetzt werden.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arbrea-labs.com\/de\/die-versteckten-risiken-der-verwendung-von-externen-sizern-und-vorher-nachher-fotos-bei-asthetischen-beratungen\/","og_locale":"de_DE","og_type":"article","og_title":"The Hidden Risks of Relying on External Sizers and Before-and-After Photos in Aesthetic Consultations","og_description":"Stay ahead in the world of plastic surgery. Learn why traditional methods like external sizers are being replaced by more advanced techniques.","og_url":"https:\/\/arbrea-labs.com\/de\/die-versteckten-risiken-der-verwendung-von-externen-sizern-und-vorher-nachher-fotos-bei-asthetischen-beratungen\/","og_site_name":"Arbrea Labs","article_publisher":"https:\/\/www.facebook.com\/arbrealabs","article_published_time":"2024-11-08T16:37:54+00:00","article_modified_time":"2025-02-20T16:34:32+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/arbrea-labs.com\/wp-content\/uploads\/2024\/11\/Untitled-design-2024-11-08T175559.659.png","type":"image\/png"}],"author":"Selene Cabibbo","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Selene Cabibbo","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/arbrea-labs.com\/the-hidden-risks-of-relying-on-external-sizers-and-before-and-after-photos-in-aesthetic-consultations\/#article","isPartOf":{"@id":"https:\/\/arbrea-labs.com\/the-hidden-risks-of-relying-on-external-sizers-and-before-and-after-photos-in-aesthetic-consultations\/"},"author":{"name":"Selene Cabibbo","@id":"https:\/\/arbrea-labs.com\/#\/schema\/person\/016c4a63167f71667e28da2b91c9e25d"},"headline":"The Hidden Risks of Relying on External Sizers and Before-and-After Photos in Aesthetic Consultations","datePublished":"2024-11-08T16:37:54+00:00","dateModified":"2025-02-20T16:34:32+00:00","mainEntityOfPage":{"@id":"https:\/\/arbrea-labs.com\/the-hidden-risks-of-relying-on-external-sizers-and-before-and-after-photos-in-aesthetic-consultations\/"},"wordCount":2358,"publisher":{"@id":"https:\/\/arbrea-labs.com\/#organization"},"image":{"@id":"https:\/\/arbrea-labs.com\/the-hidden-risks-of-relying-on-external-sizers-and-before-and-after-photos-in-aesthetic-consultations\/#primaryimage"},"thumbnailUrl":"https:\/\/arbrea-labs.com\/wp-content\/uploads\/2024\/11\/Untitled-design-2024-11-08T175559.659.png","articleSection":["Marketing &amp; Sales Tips"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/arbrea-labs.com\/the-hidden-risks-of-relying-on-external-sizers-and-before-and-after-photos-in-aesthetic-consultations\/","url":"https:\/\/arbrea-labs.com\/the-hidden-risks-of-relying-on-external-sizers-and-before-and-after-photos-in-aesthetic-consultations\/","name":"Externe Sizer: Sind sie in der modernen Welt \u00fcberholt? - Arbrea-Labore","isPartOf":{"@id":"https:\/\/arbrea-labs.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/arbrea-labs.com\/the-hidden-risks-of-relying-on-external-sizers-and-before-and-after-photos-in-aesthetic-consultations\/#primaryimage"},"image":{"@id":"https:\/\/arbrea-labs.com\/the-hidden-risks-of-relying-on-external-sizers-and-before-and-after-photos-in-aesthetic-consultations\/#primaryimage"},"thumbnailUrl":"https:\/\/arbrea-labs.com\/wp-content\/uploads\/2024\/11\/Untitled-design-2024-11-08T175559.659.png","datePublished":"2024-11-08T16:37:54+00:00","dateModified":"2025-02-20T16:34:32+00:00","description":"Bleiben Sie in der Welt der plastischen Chirurgie auf dem Laufenden. Erfahren Sie, warum traditionelle Methoden wie externe Sizer durch modernere Techniken ersetzt werden.","breadcrumb":{"@id":"https:\/\/arbrea-labs.com\/the-hidden-risks-of-relying-on-external-sizers-and-before-and-after-photos-in-aesthetic-consultations\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arbrea-labs.com\/the-hidden-risks-of-relying-on-external-sizers-and-before-and-after-photos-in-aesthetic-consultations\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/arbrea-labs.com\/the-hidden-risks-of-relying-on-external-sizers-and-before-and-after-photos-in-aesthetic-consultations\/#primaryimage","url":"https:\/\/arbrea-labs.com\/wp-content\/uploads\/2024\/11\/Untitled-design-2024-11-08T175559.659.png","contentUrl":"https:\/\/arbrea-labs.com\/wp-content\/uploads\/2024\/11\/Untitled-design-2024-11-08T175559.659.png","width":1920,"height":1080,"caption":"External Sizers"},{"@type":"BreadcrumbList","@id":"https:\/\/arbrea-labs.com\/the-hidden-risks-of-relying-on-external-sizers-and-before-and-after-photos-in-aesthetic-consultations\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/arbrea-labs.com\/"},{"@type":"ListItem","position":2,"name":"The Hidden Risks of Relying on External Sizers and Before-and-After Photos in Aesthetic Consultations"}]},{"@type":"WebSite","@id":"https:\/\/arbrea-labs.com\/#website","url":"https:\/\/arbrea-labs.com\/","name":"Arbrea-Labore","description":"Augmented Reality &amp; 3D-L\u00f6sungen f\u00fcr die \u00c4sthetik","publisher":{"@id":"https:\/\/arbrea-labs.com\/#organization"},"alternateName":"Arbrea","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arbrea-labs.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/arbrea-labs.com\/#organization","name":"Arbrea-Labore","alternateName":"Arbrea","url":"https:\/\/arbrea-labs.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/arbrea-labs.com\/#\/schema\/logo\/image\/","url":"https:\/\/arbrea-labs.com\/wp-content\/uploads\/2022\/01\/logo_arbrea_LABS-01-1-e1641392734450.png","contentUrl":"https:\/\/arbrea-labs.com\/wp-content\/uploads\/2022\/01\/logo_arbrea_LABS-01-1-e1641392734450.png","width":2000,"height":750,"caption":"Arbrea Labs"},"image":{"@id":"https:\/\/arbrea-labs.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/arbrealabs","https:\/\/www.instagram.com\/arbrealabs\/","https:\/\/www.linkedin.com\/company\/arbrea-labs-ag\/","https:\/\/www.youtube.com\/channel\/UCbHN9gofXJv8rMAHcAguTcg"],"description":"Arbrea Labs ist f\u00fchrend in der Verbindung von fortschrittlicher KI-Technologie mit personalisierter Medizin. Unsere schnellen, einfachen und sicheren Augmented Reality- und 3D-Simulatoren optimieren Beratungsgespr\u00e4che, sparen Zeit und verbessern die Patientenaufkl\u00e4rung. Gleichzeitig verbessert unser AR-gesteuerter Marketing-Booster die Patientenreise, maximiert den Marketing-ROI und f\u00f6rdert die effiziente Lead-Generierung. Gestalten Sie mit uns die Zukunft der \u00e4sthetischen Medizin.","email":"info@arbrea-labs.com","legalName":"Arbrea Labs AG","foundingDate":"2018-03-04","vatID":"CHE-292.633.177","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}},{"@type":"Person","@id":"https:\/\/arbrea-labs.com\/#\/schema\/person\/016c4a63167f71667e28da2b91c9e25d","name":"Selene Cabibbo","description":"Selene Cabibbo ist Marketing Managerin bei Arbrea Labs und darauf spezialisiert, das Wachstum durch innovative Marketingstrategien zu f\u00f6rdern. Mit einem starken Fokus auf die F\u00f6rderung von AR- und 3D-Simulationstechnologien f\u00fcr die plastische Chirurgie widmet sie sich der Steigerung der Markenpr\u00e4senz und der Kontaktaufnahme mit Zielgruppen weltweit.","sameAs":["http:\/\/arbrea-labs.com","https:\/\/www.linkedin.com\/in\/selene-cabibbo\/"],"knowsAbout":["Copywriting","Marketing strategy","Digital Marketing","Healthcare Marketing","Medical Aesthetic Marketing","Plastic Surgery Marketing","SEO","Social Media Management"],"knowsLanguage":["Italian","English","Spanish"],"jobTitle":"Marketing Manager","url":"https:\/\/arbrea-labs.com\/de\/author\/d2eea4cfe95a969b\/"}]}},"_links":{"self":[{"href":"https:\/\/arbrea-labs.com\/de\/wp-json\/wp\/v2\/posts\/39190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arbrea-labs.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arbrea-labs.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arbrea-labs.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/arbrea-labs.com\/de\/wp-json\/wp\/v2\/comments?post=39190"}],"version-history":[{"count":0,"href":"https:\/\/arbrea-labs.com\/de\/wp-json\/wp\/v2\/posts\/39190\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arbrea-labs.com\/de\/wp-json\/wp\/v2\/media\/39200"}],"wp:attachment":[{"href":"https:\/\/arbrea-labs.com\/de\/wp-json\/wp\/v2\/media?parent=39190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arbrea-labs.com\/de\/wp-json\/wp\/v2\/categories?post=39190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arbrea-labs.com\/de\/wp-json\/wp\/v2\/tags?post=39190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}